{"id":82,"count":1,"description":"","link":"http:\/\/purchaze.com\/news-de\/tag\/denim\/","name":"Denim","slug":"denim","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Denim Archives - Sneaker News - Neuheiten &amp; Hintergrundwissen - Purchaze<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/purchaze.com\/news-de\/tag\/denim\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Denim Archives - Sneaker News - Neuheiten &amp; Hintergrundwissen - Purchaze\" \/>\n<meta property=\"og:url\" content=\"http:\/\/purchaze.com\/news-de\/tag\/denim\/\" \/>\n<meta property=\"og:site_name\" content=\"Sneaker News - Neuheiten &amp; Hintergrundwissen - Purchaze\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/purchaze.com\/news-de\/tag\/denim\/\",\"url\":\"http:\/\/purchaze.com\/news-de\/tag\/denim\/\",\"name\":\"Denim Archives - Sneaker News - Neuheiten &amp; Hintergrundwissen - Purchaze\",\"isPartOf\":{\"@id\":\"http:\/\/purchaze.com\/news-de\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/purchaze.com\/news-de\/tag\/denim\/#breadcrumb\"},\"inLanguage\":\"de-DE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/purchaze.com\/news-de\/tag\/denim\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/purchaze.com\/news-de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Denim\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/purchaze.com\/news-de\/#website\",\"url\":\"http:\/\/purchaze.com\/news-de\/\",\"name\":\"Sneaker News - Neuheiten &amp; Hintergrundwissen - Purchaze\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/purchaze.com\/news-de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Denim Archives - Sneaker News - Neuheiten &amp; Hintergrundwissen - Purchaze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/purchaze.com\/news-de\/tag\/denim\/","og_locale":"de_DE","og_type":"article","og_title":"Denim Archives - Sneaker News - Neuheiten &amp; Hintergrundwissen - Purchaze","og_url":"http:\/\/purchaze.com\/news-de\/tag\/denim\/","og_site_name":"Sneaker News - Neuheiten &amp; Hintergrundwissen - Purchaze","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/purchaze.com\/news-de\/tag\/denim\/","url":"http:\/\/purchaze.com\/news-de\/tag\/denim\/","name":"Denim Archives - Sneaker News - Neuheiten &amp; Hintergrundwissen - Purchaze","isPartOf":{"@id":"http:\/\/purchaze.com\/news-de\/#website"},"breadcrumb":{"@id":"http:\/\/purchaze.com\/news-de\/tag\/denim\/#breadcrumb"},"inLanguage":"de-DE"},{"@type":"BreadcrumbList","@id":"http:\/\/purchaze.com\/news-de\/tag\/denim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/purchaze.com\/news-de\/"},{"@type":"ListItem","position":2,"name":"Denim"}]},{"@type":"WebSite","@id":"http:\/\/purchaze.com\/news-de\/#website","url":"http:\/\/purchaze.com\/news-de\/","name":"Sneaker News - Neuheiten &amp; Hintergrundwissen - Purchaze","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/purchaze.com\/news-de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"http:\/\/purchaze.com\/news-de\/wp-json\/wp\/v2\/tags\/82"}],"collection":[{"href":"http:\/\/purchaze.com\/news-de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/purchaze.com\/news-de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/purchaze.com\/news-de\/wp-json\/wp\/v2\/posts?tags=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}